{"id":13759,"date":"2025-10-22T10:24:18","date_gmt":"2025-10-22T08:24:18","guid":{"rendered":"https:\/\/www.seniorenakademie.dhbw-heidenheim.de\/?post_type=tribe_events&#038;p=13759"},"modified":"2025-10-22T10:24:35","modified_gmt":"2025-10-22T08:24:35","slug":"von-der-backstube-in-den-landtag-und-zurueck-abgeordneter-in-unruhigen-zeiten","status":"publish","type":"tribe_events","link":"https:\/\/www.seniorenakademie.dhbw-heidenheim.de\/index.php\/event\/von-der-backstube-in-den-landtag-und-zurueck-abgeordneter-in-unruhigen-zeiten\/","title":{"rendered":"Von der Backstube in den Landtag und zur\u00fcck &#8211; Abgeordneter in unruhigen Zeiten"},"content":{"rendered":"<p>Martin Grath im Raum 108 in der Wilhelmstra\u00dfe<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Martin Grath im Raum 108 in der Wilhelmstra\u00dfe<\/p>\n","protected":false},"author":10,"featured_media":0,"template":"","meta":{"_crdt_document":"","_themeisle_gutenberg_block_has_review":false,"_tribe_events_status":"","_tribe_events_status_reason":"","_tribe_events_is_hybrid":"","_tribe_events_is_virtual":"","_tribe_events_virtual_video_source":"","_tribe_events_virtual_embed_video":"","_tribe_events_virtual_linked_button_text":"","_tribe_events_virtual_linked_button":"","_tribe_events_virtual_show_embed_at":"","_tribe_events_virtual_show_embed_to":[],"_tribe_events_virtual_show_on_event":"","_tribe_events_virtual_show_on_views":"","_tribe_events_virtual_url":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-13759","tribe_events","type-tribe_events","status-publish","hentry","gallery-content-unit"],"_links":{"self":[{"href":"https:\/\/www.seniorenakademie.dhbw-heidenheim.de\/index.php\/wp-json\/wp\/v2\/tribe_events\/13759","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.seniorenakademie.dhbw-heidenheim.de\/index.php\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.seniorenakademie.dhbw-heidenheim.de\/index.php\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.seniorenakademie.dhbw-heidenheim.de\/index.php\/wp-json\/wp\/v2\/users\/10"}],"version-history":[{"count":1,"href":"https:\/\/www.seniorenakademie.dhbw-heidenheim.de\/index.php\/wp-json\/wp\/v2\/tribe_events\/13759\/revisions"}],"predecessor-version":[{"id":13760,"href":"https:\/\/www.seniorenakademie.dhbw-heidenheim.de\/index.php\/wp-json\/wp\/v2\/tribe_events\/13759\/revisions\/13760"}],"wp:attachment":[{"href":"https:\/\/www.seniorenakademie.dhbw-heidenheim.de\/index.php\/wp-json\/wp\/v2\/media?parent=13759"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.seniorenakademie.dhbw-heidenheim.de\/index.php\/wp-json\/wp\/v2\/tags?post=13759"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.seniorenakademie.dhbw-heidenheim.de\/index.php\/wp-json\/wp\/v2\/tribe_events_cat?post=13759"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}